{"id":9391,"date":"2026-05-09T19:34:47","date_gmt":"2026-05-09T19:34:47","guid":{"rendered":"https:\/\/auctionafrique.co.uk\/2026\/05\/09\/montee-des-restrictions-a-lexportation-de-matieres-premieres-critiques\/"},"modified":"2026-05-09T19:34:47","modified_gmt":"2026-05-09T19:34:47","slug":"montee-des-restrictions-a-lexportation-de-matieres-premieres-critiques","status":"publish","type":"post","link":"https:\/\/auctionafrique.co.uk\/ar\/2026\/05\/09\/montee-des-restrictions-a-lexportation-de-matieres-premieres-critiques\/","title":{"rendered":"Mont\u00e9e des restrictions \u00e0 l\u2019exportation de mati\u00e8res premi\u00e8res critiques"},"content":{"rendered":"<p><br \/>\n<\/p>\n<div>\n\t\t\t\t\t Le nombre de restrictions \u00e0 l\u2019exportation visant plusieurs min\u00e9raux strat\u00e9giques pour les technologies du num\u00e9rique et des \u00e9nergies renouvelables continue d\u2019augmenter, constate l&rsquo;Organisation de coop\u00e9ration et de d\u00e9veloppement \u00e9conomiques (OCDE) dans un nouveau rapport. <br \/>  \u00a0  <\/p>\n<blockquote><p><strong><span style=\"color:#FF0000;\">Les mesures visant les produits d\u2019amont, comme les minerais et min\u00e9raux, ont explos\u00e9 entre 2009 et 2024, selon l\u2019OCDE<\/span><\/strong><\/p><\/blockquote>\n<p>  Selon le document, qui analyse les restrictions \u00e0 l\u2019exportation de mati\u00e8res premi\u00e8res critiques mises en place jusqu\u2019\u00e0 fin 2024,\u00a0 leur nombre n\u2019a cess\u00e9 de cro\u00eetre ces 15 derni\u00e8res ann\u00e9es au point d\u2019atteindre d\u00e9sormais un niveau record. <\/p>\n<p>Intitul\u00e9e \u00abL\u2019Inventaire des restrictions \u00e0 l\u2019exportation de mati\u00e8res premi\u00e8res critiques\u00bb, la nouvelle version dudit rapport montre que les mesures particuli\u00e8rement restrictives, comme les interdictions d\u2019exportation et le contingentement, gagnent du terrain. D\u2019apr\u00e8s le document \u00e9tabli annuellement, elles repr\u00e9sentaient plus d\u2019un tiers des nouvelles restrictions mises en place en 2024. <\/p>\n<p>La m\u00eame source r\u00e9v\u00e8le par ailleurs que la g\u00e9n\u00e9ration de recettes est devenue, depuis les ann\u00e9es 2010, la principale raison avanc\u00e9e pour justifier l\u2019adoption de restrictions \u00e0 l\u2019exportation. En 2024, elle a m\u00eame occup\u00e9 la premi\u00e8re place, \u00e9tant invoqu\u00e9e dans pr\u00e8s de la moiti\u00e9 des cas. <\/p>\n<p>Bien que leur progression ait marqu\u00e9 le pas, en passant de 3.4 % en 2023 \u00e0 0.6 % en 2024, l\u2019organisation note que l\u2019\u00e9ventail des pays mettant en place de telles restrictions s\u2019est \u00e9largi, en particulier en Afrique et en Asie. <br \/>Elle constate aussi que \u00ab\u00a0certaines ressources min\u00e9rales essentielles aux syst\u00e8mes \u00e9nerg\u00e9tiques, comme le cobalt, le mangan\u00e8se, le graphite et les terres rares, sont particuli\u00e8rement touch\u00e9es par les restrictions \u00e0 l\u2019export\u00a0\u00bb. <\/p>\n<p>La nouvelle \u00e9dition du rapport pr\u00e9cise qu\u2019environ 70% des exportations mondiales de cobalt et de mangan\u00e8se ont fait l\u2019objet d\u2019au moins une mesure de cette nature entre 2022 et 2024, de m\u00eame que 16% des \u00e9changes de mati\u00e8res premi\u00e8res critiques suivis par l\u2019OCDE au cours de la m\u00eame p\u00e9riode. <\/p>\n<p>L\u2019analyse des donn\u00e9es recueillies montre que les d\u00e9chets et d\u00e9bris formaient toujours la cat\u00e9gorie de mati\u00e8res premi\u00e8res critiques la plus vis\u00e9e par des restrictions \u00e0 l\u2019exportation en 2024, \u00ab\u00a0en raison des pr\u00e9occupations environnementales et de l\u2019int\u00e9r\u00eat grandissant pour l\u2019\u00e9conomie circulaire comme source de m\u00e9taux et ressources min\u00e9rales\u00a0\u00bb, a indiqu\u00e9 l\u2019organisation, soulignant, par ailleurs, que le nombre des restrictions \u00e0 l\u2019exportation de produits d\u2019amont comme les minerais et min\u00e9raux a grimp\u00e9 en fl\u00e8che entre 2009 et 2024, p\u00e9riode au cours de laquelle il a d\u00e9cupl\u00e9. <\/p>\n<p>M\u00eame si les principaux producteurs diff\u00e8rent selon les minerais, trois pays concentrent plus des deux tiers de la production mondiale dans les cas du cobalt, du lithium et du nickel, et pr\u00e8s de 90% dans le cas des terres rares. <br \/>Les auteurs du rapport font \u00e9galement \u00e9tat d\u2019une concentration des mesures : l\u2019Inde (19%), la Chine (17%), l\u2019Argentine (6%), le Viet Nam (5%) et le Burundi (4%) repr\u00e9sentent plus de la moiti\u00e9 des nouvelles restrictions \u00e0 l\u2019export adopt\u00e9es entre 2009 et 2024. <\/p>\n<p>La mont\u00e9e des restrictions \u00e0 l\u2019exportation de mati\u00e8res premi\u00e8res critiques constitue une menace pour la croissance \u00e9conomique, l\u2019innovation et la s\u00e9curit\u00e9 \u00e9nerg\u00e9tique de nombreux pays tributaires d\u2019un acc\u00e8s fiable aux mati\u00e8res premi\u00e8res critiques, estime l\u2019OCDE expliquant que cette \u00e9volution accro\u00eet les risques pour les cha\u00eenes d\u2019approvisionnement mondiales. <\/p>\n<p>Lors du Forum de l\u2019OCDE sur les min\u00e9raux critiques \u00e0 Istanbul, le Secr\u00e9taire g\u00e9n\u00e9ral de l\u2019OCDE, Mathias Cormann, s\u2019est exprim\u00e9 sur la question en ces termes\u00a0: \u00abLes restrictions \u00e0 l\u2019export peuvent aggraver les vuln\u00e9rabilit\u00e9s des cha\u00eenes d\u2019approvisionnement fortement concentr\u00e9es en limitant les volumes export\u00e9s et en tirant les prix \u00e0 la hausse\u00a0\u00bb. <\/p>\n<p>De l\u2019avis de ce dernier, \u00ab\u00a0il est fondamental de rendre ces mesures plus transparentes pour favoriser l\u2019ouverture et la diversification des march\u00e9s des min\u00e9raux critiques, pour faciliter les investissements\u00a0\u00bb n\u00e9cessaires au d\u00e9veloppement de la production et pour favoriser l\u2019instauration de partenariats mutuellement b\u00e9n\u00e9fiques avec les pays producteurs\u00bb. <\/p>\n<p><strong>Alain Bouithy<\/strong>\n\t\t\t\t <\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.libe.ma\/Montee-des-restrictions-a-l-exportation-de-matieres-premieres-critiques_a161199.html\">Source link <\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Le nombre de restrictions \u00e0 l\u2019exportation visant plusieurs min\u00e9raux strat\u00e9giques pour les technologies du num\u00e9rique et des \u00e9nergies renouvelables continue<\/p>","protected":false},"author":30,"featured_media":9392,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"googlesitekit_rrm_CAow1p3FDA:productID":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-9391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/auctionafrique.co.uk\/wp-content\/uploads\/2026\/05\/96461844-67263497.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/auctionafrique.co.uk\/ar\/wp-json\/wp\/v2\/posts\/9391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auctionafrique.co.uk\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/auctionafrique.co.uk\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/auctionafrique.co.uk\/ar\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/auctionafrique.co.uk\/ar\/wp-json\/wp\/v2\/comments?post=9391"}],"version-history":[{"count":0,"href":"https:\/\/auctionafrique.co.uk\/ar\/wp-json\/wp\/v2\/posts\/9391\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auctionafrique.co.uk\/ar\/wp-json\/wp\/v2\/media\/9392"}],"wp:attachment":[{"href":"https:\/\/auctionafrique.co.uk\/ar\/wp-json\/wp\/v2\/media?parent=9391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/auctionafrique.co.uk\/ar\/wp-json\/wp\/v2\/categories?post=9391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/auctionafrique.co.uk\/ar\/wp-json\/wp\/v2\/tags?post=9391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}